{"id":421,"date":"2025-05-14T09:39:18","date_gmt":"2025-05-14T07:39:18","guid":{"rendered":"https:\/\/econau.org\/comunidad-corresponsable\/"},"modified":"2026-05-08T12:10:22","modified_gmt":"2026-05-08T10:10:22","slug":"comunidad-corresponsable","status":"publish","type":"page","link":"https:\/\/econau.org\/es\/comunidad-corresponsable\/","title":{"rendered":"COMUNIDAD CORRESPONSABLE"},"content":{"rendered":"\n<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_0 et_pb_row et_block_row\"><div class=\"et_pb_column_0 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_center preset--module--divi-text--c0ce4143-8edb-4eef-9f6e-6cb406e66847\"><div class=\"et_pb_text_inner\"><h1 style=\"text-align: left;\">Comunidad corresponsable<\/h1>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_1 et_pb_row et_block_row\"><div class=\"et_pb_column_1 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>La <strong>Comunidad Corresponsable<\/strong> es mucho m\u00e1s que una forma de consumir: es una forma de <strong>comprometernos juntas con la tierra y con quien la cultiva.<\/strong><\/p>\n<p>Nos inspiramos en modelos de consumo \u00e9tico como las <strong>AMAP<\/strong> (Francia), los <strong>GAS\/GAP<\/strong> (Italia) o las <strong>CSA<\/strong> (EEUU), en los que productoras y consumidoras comparten responsabilidad, riesgos y frutos en torno a un proyecto agr\u00edcola. Es una forma concreta de garantizar la <strong>r<\/strong>esiliencia de las peque\u00f1as productoras de productos ecol\u00f3gicos, locales y sostenibles, <strong>tejiendo v\u00ednculos humanos y solidarios.<\/strong><\/p>\n<h3><strong>A partir de 2025... \u00a1nace nuestra Comunidad Corresponsable!<\/strong><\/h3>\n<p>Con una <strong>cuota anual justa y adaptada<\/strong> (individual, familiar o por empresas), formar\u00e1s parte de un sistema que:<\/p>\n<ul>\n<li>Te da acceso a <strong>lotes exclusivos de productos de temporada<\/strong><\/li>\n<li>Ofrece <strong>descuentos en productos y actividades<\/strong><\/li>\n<li>Te invita a <strong>participar activamente en el proyecto<\/strong>, si lo deseas, aportando tu mirada y capacidades<\/li>\n<\/ul>\n<p>Es una forma de <strong>dar apoyo real al territorio<\/strong>, a la agricultura con valores, ya una econom\u00eda m\u00e1s justa, sostenible y comunitaria.<\/p>\n<h3><strong>\u00a1\u00danete a la comunidad agroecol\u00f3gica del EcoNau!<\/strong><\/h3>\n<p>Env\u00edanos un correo a: info.econau@gmail.com<\/p>\n<h3><strong>Tipo de cuotas<\/strong><\/h3>\n<p>Para formar parte de la Comunidad Corresponsable del EcoNau, puedes elegir la cuota que mejor se adapte a ti:<\/p>\n<ul>\n<li><strong>Cuota Individual<\/strong>: pensada para personas que quieren implicarse y consumir de forma consciente y comprometida.<\/li>\n<li><strong>Cuota Familiar<\/strong>: ideal para hogares que desean acceder a lotes m\u00e1s completos y participar en actividades adaptadas a peque\u00f1os y mayores.<\/li>\n<li><strong>Quota per a Empreses o Col\u00b7lectius<\/strong>: adre\u00e7ada a projectes, restaurants, entitats o comer\u00e7os que aposten per una economia local i ecol\u00f2gica.<\/li>\n<\/ul>\n<p>Todas las cuotas incluyen ventajas en productos y actividades, contribuyendo directamente al sostenimiento del proyecto.<br \/><span> <\/span><strong>\u00a1Elige la tuya y s\u00e9 parte del cambio!<\/strong><\/p>\n<\/div><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper preset--module--divi-button--0847f104-f625-41e1-b9a7-52ade071f13f_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--0847f104-f625-41e1-b9a7-52ade071f13f\" href=\"https:\/\/econau.org\/fes-ten-soci\/\">\u00a1HAZTE SOCIO!<\/a><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-421","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMUNIDAD CORRESPONSABLE - Econau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/econau.org\/es\/comunidad-corresponsable\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMUNIDAD CORRESPONSABLE - Econau\" \/>\n<meta property=\"og:url\" content=\"https:\/\/econau.org\/es\/comunidad-corresponsable\/\" \/>\n<meta property=\"og:site_name\" content=\"Econau\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T10:10:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/econau.org\\\/es\\\/comunidad-corresponsable\\\/\",\"url\":\"https:\\\/\\\/econau.org\\\/es\\\/comunidad-corresponsable\\\/\",\"name\":\"COMUNIDAD CORRESPONSABLE - Econau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/econau.org\\\/#website\"},\"datePublished\":\"2025-05-14T07:39:18+00:00\",\"dateModified\":\"2026-05-08T10:10:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/econau.org\\\/es\\\/comunidad-corresponsable\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/econau.org\\\/es\\\/comunidad-corresponsable\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/econau.org\\\/es\\\/comunidad-corresponsable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/econau.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMUNIDAD CORRESPONSABLE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/econau.org\\\/#website\",\"url\":\"https:\\\/\\\/econau.org\\\/\",\"name\":\"Econau\",\"description\":\"Empoderem la garrofa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/econau.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMUNIDAD CORRESPONSABLE - Econau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/econau.org\/es\/comunidad-corresponsable\/","og_locale":"es_ES","og_type":"article","og_title":"COMUNIDAD CORRESPONSABLE - Econau","og_url":"https:\/\/econau.org\/es\/comunidad-corresponsable\/","og_site_name":"Econau","article_modified_time":"2026-05-08T10:10:22+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/econau.org\/es\/comunidad-corresponsable\/","url":"https:\/\/econau.org\/es\/comunidad-corresponsable\/","name":"COMUNIDAD CORRESPONSABLE - Econau","isPartOf":{"@id":"https:\/\/econau.org\/#website"},"datePublished":"2025-05-14T07:39:18+00:00","dateModified":"2026-05-08T10:10:22+00:00","breadcrumb":{"@id":"https:\/\/econau.org\/es\/comunidad-corresponsable\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/econau.org\/es\/comunidad-corresponsable\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/econau.org\/es\/comunidad-corresponsable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/econau.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"COMUNIDAD CORRESPONSABLE"}]},{"@type":"WebSite","@id":"https:\/\/econau.org\/#website","url":"https:\/\/econau.org\/","name":"Econau","description":"Empoderem la garrofa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/econau.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/econau.org\/es\/wp-json\/wp\/v2\/pages\/421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econau.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/econau.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/econau.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/econau.org\/es\/wp-json\/wp\/v2\/comments?post=421"}],"version-history":[{"count":2,"href":"https:\/\/econau.org\/es\/wp-json\/wp\/v2\/pages\/421\/revisions"}],"predecessor-version":[{"id":1740,"href":"https:\/\/econau.org\/es\/wp-json\/wp\/v2\/pages\/421\/revisions\/1740"}],"wp:attachment":[{"href":"https:\/\/econau.org\/es\/wp-json\/wp\/v2\/media?parent=421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}